{"id":24800,"date":"2018-04-19T14:17:20","date_gmt":"2018-07-02T09:50:31","guid":{"rendered":"https:\/\/bacsa.es\/producto\/indicateur-de-poids-i40\/"},"modified":"2020-04-29T21:17:52","modified_gmt":"2020-04-29T19:17:52","slug":"indicateur-de-poids-i40","status":"publish","type":"product","link":"https:\/\/bacsa.es\/fr\/producto\/indicateur-de-poids-i40\/","title":{"rendered":"Indicateur de Poids I40"},"content":{"rendered":"<p> Principales caract\u00e9ristiques <\/ p><\/p>\n<ul>\n<li> L&#8217;indicateur industriel I40 est particuli\u00e8rement adapt\u00e9 au pesage de process en s&#8217;int\u00e9grant facilement dans tout processus industriel de mesure de poids. <\/ li>\n<li> Les nombreuses possibilit\u00e9s de connexion permettent une connexion directe de l&#8217;indicateur I40 \u00e0 la plupart des API et PC industriels du march\u00e9. <\/ li>\n<li> Les diff\u00e9rents bo\u00eetiers permettent d&#8217;installer un indicateur directement dans l&#8217;environnement de travail, dans une armoire ou un pupitre de commande. <\/ li>\n<li> Les diff\u00e9rents bo\u00eetiers permettent d&#8217;installer un indicateur directement dans l&#8217;environnement de travail, dans une armoire ou un pupitre de commande. <\/ li>\n<li> L&#8217;indicateur I40 est disponible pour ATEX Zone 2-22. Selon la directive 94\/9 \/ CE, il peut \u00eatre install\u00e9 dans les risques de zones dangereuses associ\u00e9es \u00e0 la pr\u00e9sence de poussi\u00e8res (zone 22) et \/ ou de gaz (zone 2). <\/ Li><br \/>\n<\/ ul><\/p>\n<p> Fonctionnalit\u00e9s <\/ p><\/p>\n<ul>\n<li> Communication\n<ul>\n<li> 1 port configurable RS232 \/ RS485. <\/ li>\n<li> Protocoles: esclave Modbus RTU, esclave PM A + et r\u00e9p\u00e9teur ma\u00eetre PM A +. <\/ li><br \/>\n    <\/ ul><br \/>\n  <\/ li><\/p>\n<li> Seuils de poids\n<ul>\n<li> 4 sorties num\u00e9riques 48 V AC \/ DC &#8211; isolation galvanique 100 mA. <\/ li>\n<li> D\u00e9finition des seuils en poids brut ou en poids net. <\/ li>\n<li> Activation de la sortie si le poids est> = ou <= la valeur de seuil. <\/ li>\n<li> Seuils relatifs \u00e0 une valeur positive ou n\u00e9gative du poids. <\/ li><br \/>\n    <\/ ul><br \/>\n  <\/ li><\/p>\n<li> T\u00e9l\u00e9commande\n<ul>\n<li> 2 entr\u00e9es num\u00e9riques isol\u00e9es galvaniquement permettent d&#8217;effectuer \u00e0 distance les op\u00e9rations de r\u00e9initialisation et de tarage. <\/ li><br \/>\n    <\/ ul><br \/>\n  <\/ li><\/p>\n<li> Configuration\n<ul>\n<li> La configuration m\u00e9trologique et fonctionnelle de l&#8217;indicateur peut \u00eatre r\u00e9alis\u00e9e:\n<ul>\n<li> Par le cadran de l&#8217;indicateur. <\/ li>\n<li> Via un PC et un simple navigateur Internet. <\/ li><br \/>\n        <\/ ul><br \/>\n      <\/ li><\/p>\n<li> Sauvegarde \/ restauration des param\u00e8tres dans une carte \u03bcSD (option) ou un disque PC. <\/ li><br \/>\n    <\/ ul><br \/>\n  <\/ li><\/p>\n<li> Aide \u00e0 la maintenance pr\u00e9ventive\n<ul>\n<li> Compteur de surcharge des poids v\u00e9rifi\u00e9s. <\/ li>\n<li> Les alertes s&#8217;affichent sur 3 niveaux en fonction du nombre de pes\u00e9es effectu\u00e9es. <\/ li><br \/>\n    <\/ ul><br \/>\n  <\/ li><br \/>\n<\/ ul><\/p>\n","protected":false},"excerpt":{"rendered":"<ul>\n<li> L&#8217;indicateur industriel I40 est particuli\u00e8rement adapt\u00e9 au pesage de process en s&#8217;int\u00e9grant facilement dans tout processus industriel de mesure de poids. <\/ li>\n<li> Les nombreuses possibilit\u00e9s de connexion permettent une connexion directe de l&#8217;indicateur I40 \u00e0 la plupart des API et PC industriels du march\u00e9. <\/ li>\n<li> Les diff\u00e9rents bo\u00eetiers permettent d&#8217;installer un indicateur directement dans l&#8217;environnement de travail, dans une armoire ou un pupitre de commande. <\/ li><br \/>\n<\/ ul><\/p>\n","protected":false},"featured_media":9169,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[1310,1405,1317,1411,1308,1316,1315,1248,1311,1312,1273,1276],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Indicador de peso I40<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bacsa.es\/fr\/producto\/indicateur-de-poids-i40\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Indicador de peso I40\" \/>\n<meta property=\"og:description\" content=\"L&#039;indicateur industriel I40 est particuli\u00e8rement adapt\u00e9 au pesage de process en s&#039;int\u00e9grant facilement dans tout processus industriel de mesure de poids.   Les nombreuses possibilit\u00e9s de connexion permettent une connexion directe de l&#039;indicateur I40 \u00e0 la plupart des API et PC industriels du march\u00e9.   Les diff\u00e9rents bo\u00eetiers permettent d&#039;installer un indicateur directement dans l&#039;environnement de travail, dans une armoire ou un pupitre de commande.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bacsa.es\/fr\/producto\/indicateur-de-poids-i40\/\" \/>\n<meta property=\"og:site_name\" content=\"Bacsa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Bacsa-142507322476303\/\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-29T19:17:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bacsa.es\/wp-content\/uploads\/2018\/01\/Bacsa-Indicador-I40.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@BACSA_PESAJE\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bacsa.es\/fr\/producto\/indicateur-de-poids-i40\/\",\"url\":\"https:\/\/bacsa.es\/fr\/producto\/indicateur-de-poids-i40\/\",\"name\":\"Indicador de peso I40\",\"isPartOf\":{\"@id\":\"https:\/\/bacsa.es\/#website\"},\"datePublished\":\"2018-07-02T09:50:31+00:00\",\"dateModified\":\"2020-04-29T19:17:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/bacsa.es\/fr\/producto\/indicateur-de-poids-i40\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bacsa.es\/fr\/producto\/indicateur-de-poids-i40\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bacsa.es\/fr\/producto\/indicateur-de-poids-i40\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/bacsa.es\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\/\/bacsa.es\/fr\/boutique\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Indicateur de Poids I40\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bacsa.es\/#website\",\"url\":\"https:\/\/bacsa.es\/\",\"name\":\"Bacsa\",\"description\":\"Calidad de Peso\",\"publisher\":{\"@id\":\"https:\/\/bacsa.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bacsa.es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/bacsa.es\/#organization\",\"name\":\"BACSA\",\"url\":\"https:\/\/bacsa.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/bacsa.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/bacsa.es\/wp-content\/uploads\/2019\/01\/LOGO.png\",\"contentUrl\":\"https:\/\/bacsa.es\/wp-content\/uploads\/2019\/01\/LOGO.png\",\"width\":1000,\"height\":215,\"caption\":\"BACSA\"},\"image\":{\"@id\":\"https:\/\/bacsa.es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Bacsa-142507322476303\/\",\"https:\/\/twitter.com\/BACSA_PESAJE\",\"https:\/\/www.linkedin.com\/company\/bacsa\/\",\"https:\/\/www.youtube.com\/channel\/UCGm8hAnr6kEP21vdpU3jG9g\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Indicador de peso I40","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bacsa.es\/fr\/producto\/indicateur-de-poids-i40\/","og_locale":"fr_FR","og_type":"article","og_title":"Indicador de peso I40","og_description":"L'indicateur industriel I40 est particuli\u00e8rement adapt\u00e9 au pesage de process en s'int\u00e9grant facilement dans tout processus industriel de mesure de poids.   Les nombreuses possibilit\u00e9s de connexion permettent une connexion directe de l'indicateur I40 \u00e0 la plupart des API et PC industriels du march\u00e9.   Les diff\u00e9rents bo\u00eetiers permettent d'installer un indicateur directement dans l'environnement de travail, dans une armoire ou un pupitre de commande.","og_url":"https:\/\/bacsa.es\/fr\/producto\/indicateur-de-poids-i40\/","og_site_name":"Bacsa","article_publisher":"https:\/\/www.facebook.com\/Bacsa-142507322476303\/","article_modified_time":"2020-04-29T19:17:52+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/bacsa.es\/wp-content\/uploads\/2018\/01\/Bacsa-Indicador-I40.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@BACSA_PESAJE","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bacsa.es\/fr\/producto\/indicateur-de-poids-i40\/","url":"https:\/\/bacsa.es\/fr\/producto\/indicateur-de-poids-i40\/","name":"Indicador de peso I40","isPartOf":{"@id":"https:\/\/bacsa.es\/#website"},"datePublished":"2018-07-02T09:50:31+00:00","dateModified":"2020-04-29T19:17:52+00:00","breadcrumb":{"@id":"https:\/\/bacsa.es\/fr\/producto\/indicateur-de-poids-i40\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bacsa.es\/fr\/producto\/indicateur-de-poids-i40\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bacsa.es\/fr\/producto\/indicateur-de-poids-i40\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/bacsa.es\/fr\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/bacsa.es\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"Indicateur de Poids I40"}]},{"@type":"WebSite","@id":"https:\/\/bacsa.es\/#website","url":"https:\/\/bacsa.es\/","name":"Bacsa","description":"Calidad de Peso","publisher":{"@id":"https:\/\/bacsa.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bacsa.es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/bacsa.es\/#organization","name":"BACSA","url":"https:\/\/bacsa.es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/bacsa.es\/#\/schema\/logo\/image\/","url":"https:\/\/bacsa.es\/wp-content\/uploads\/2019\/01\/LOGO.png","contentUrl":"https:\/\/bacsa.es\/wp-content\/uploads\/2019\/01\/LOGO.png","width":1000,"height":215,"caption":"BACSA"},"image":{"@id":"https:\/\/bacsa.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Bacsa-142507322476303\/","https:\/\/twitter.com\/BACSA_PESAJE","https:\/\/www.linkedin.com\/company\/bacsa\/","https:\/\/www.youtube.com\/channel\/UCGm8hAnr6kEP21vdpU3jG9g"]}]}},"_links":{"self":[{"href":"https:\/\/bacsa.es\/fr\/wp-json\/wp\/v2\/product\/24800"}],"collection":[{"href":"https:\/\/bacsa.es\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bacsa.es\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/bacsa.es\/fr\/wp-json\/wp\/v2\/comments?post=24800"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bacsa.es\/fr\/wp-json\/wp\/v2\/media\/9169"}],"wp:attachment":[{"href":"https:\/\/bacsa.es\/fr\/wp-json\/wp\/v2\/media?parent=24800"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bacsa.es\/fr\/wp-json\/wp\/v2\/product_cat?post=24800"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bacsa.es\/fr\/wp-json\/wp\/v2\/product_tag?post=24800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}