{"id":24775,"date":"2018-04-19T14:16:37","date_gmt":"2018-07-02T09:50:31","guid":{"rendered":"https:\/\/bacsa.es\/producto\/indicateur-de-poids-bdi-610\/"},"modified":"2020-04-29T21:16:46","modified_gmt":"2020-04-29T19:16:46","slug":"indicateur-de-poids-bdi-610","status":"publish","type":"product","link":"https:\/\/bacsa.es\/fr\/producto\/indicateur-de-poids-bdi-610\/","title":{"rendered":"Indicateur de Poids BDI-610"},"content":{"rendered":"<p>Fonctionnalit\u00e9s<\/p>\n<ul>\n<li>Poids-Tare- Accumulation.<\/li>\n<li>Comptage de pi\u00e8ces.<\/li>\n<li>Contr\u00f4le du poids (minimum-objectif-maximum).<\/li>\n<li>Dosage: 1 Produit \/ 2 Vitesses (avec option 4 Entr\u00e9es\/Sorties et seulement disponible pour le mod\u00e8le BDI-610 Inox).<\/li>\n<li>Contr\u00f4le du poids (avec option 4 entr\u00e9es\/Sorties et seulement disponibles pour le mod\u00e8le BDI-610).<\/li>\n<li>Sortie analogique 4-20 mA \/ 0-10 V (en option). Seulement disponible pour le mod\u00e8le BDI-610 Inox).<\/li>\n<li>Horloge en temps r\u00e9el, maintenue par batterie.<\/li>\n<li>M\u00e9moire ALIBI en option (en attente d&#8217;approbation).<\/li>\n<li>R\u00e9p\u00e9titeur.<\/li>\n<\/ul>\n<p>CPU<\/p>\n<ul>\n<li>Processeur \/ Microprocesseur: ARM 32 bit cortex M3.<\/li>\n<li>M\u00e9moire: 256 Ko Flash et 48 Ko RAM.<\/li>\n<\/ul>\n<p>Pesage<\/p>\n<ul>\n<li>Connectable \u00e0 1 plate-forme de pesage avec jusqu&#8217;\u00e0 14 capteurs.<\/li>\n<li>Lin\u00e9arisation: jusqu&#8217;\u00e0 cinq points de consigne.<\/li>\n<li>Jusqu&#8217;\u00e0 6 000 divisions. Simple, multigamme ou multi-intervalle.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les indicateurs de poids BDI-610 remplissent plusieurs fonctions dans les processus de pesage (comptage, contr\u00f4le de poids, dosage &#8230;) et peuvent \u00eatre connect\u00e9s \u00e0 des plates-formes de pesage de jusqu&#8217;\u00e0 14 cellules de pes\u00e9e.<\/p>\n","protected":false},"featured_media":9155,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[1310,1314,1313,1309,1308,1274,1316,1315,1248,1311,1312,1275,1273],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Indicador de peso BDI-610<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bacsa.es\/fr\/producto\/indicateur-de-poids-bdi-610\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Indicador de peso BDI-610\" \/>\n<meta property=\"og:description\" content=\"Les indicateurs de poids BDI-610 remplissent plusieurs fonctions dans les processus de pesage (comptage, contr\u00f4le de poids, dosage ...) et peuvent \u00eatre connect\u00e9s \u00e0 des plates-formes de pesage de jusqu&#039;\u00e0 14 cellules de pes\u00e9e.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bacsa.es\/fr\/producto\/indicateur-de-poids-bdi-610\/\" \/>\n<meta property=\"og:site_name\" content=\"Bacsa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Bacsa-142507322476303\/\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-29T19:16:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bacsa.es\/wp-content\/uploads\/2018\/01\/Bacsa-Indicador-BDI-610.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@BACSA_PESAJE\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bacsa.es\/fr\/producto\/indicateur-de-poids-bdi-610\/\",\"url\":\"https:\/\/bacsa.es\/fr\/producto\/indicateur-de-poids-bdi-610\/\",\"name\":\"Indicador de peso BDI-610\",\"isPartOf\":{\"@id\":\"https:\/\/bacsa.es\/#website\"},\"datePublished\":\"2018-07-02T09:50:31+00:00\",\"dateModified\":\"2020-04-29T19:16:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/bacsa.es\/fr\/producto\/indicateur-de-poids-bdi-610\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bacsa.es\/fr\/producto\/indicateur-de-poids-bdi-610\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bacsa.es\/fr\/producto\/indicateur-de-poids-bdi-610\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/bacsa.es\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\/\/bacsa.es\/fr\/boutique\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Indicateur de Poids BDI-610\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bacsa.es\/#website\",\"url\":\"https:\/\/bacsa.es\/\",\"name\":\"Bacsa\",\"description\":\"Calidad de Peso\",\"publisher\":{\"@id\":\"https:\/\/bacsa.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bacsa.es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/bacsa.es\/#organization\",\"name\":\"BACSA\",\"url\":\"https:\/\/bacsa.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/bacsa.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/bacsa.es\/wp-content\/uploads\/2019\/01\/LOGO.png\",\"contentUrl\":\"https:\/\/bacsa.es\/wp-content\/uploads\/2019\/01\/LOGO.png\",\"width\":1000,\"height\":215,\"caption\":\"BACSA\"},\"image\":{\"@id\":\"https:\/\/bacsa.es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Bacsa-142507322476303\/\",\"https:\/\/twitter.com\/BACSA_PESAJE\",\"https:\/\/www.linkedin.com\/company\/bacsa\/\",\"https:\/\/www.youtube.com\/channel\/UCGm8hAnr6kEP21vdpU3jG9g\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Indicador de peso BDI-610","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bacsa.es\/fr\/producto\/indicateur-de-poids-bdi-610\/","og_locale":"fr_FR","og_type":"article","og_title":"Indicador de peso BDI-610","og_description":"Les indicateurs de poids BDI-610 remplissent plusieurs fonctions dans les processus de pesage (comptage, contr\u00f4le de poids, dosage ...) et peuvent \u00eatre connect\u00e9s \u00e0 des plates-formes de pesage de jusqu'\u00e0 14 cellules de pes\u00e9e.","og_url":"https:\/\/bacsa.es\/fr\/producto\/indicateur-de-poids-bdi-610\/","og_site_name":"Bacsa","article_publisher":"https:\/\/www.facebook.com\/Bacsa-142507322476303\/","article_modified_time":"2020-04-29T19:16:46+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/bacsa.es\/wp-content\/uploads\/2018\/01\/Bacsa-Indicador-BDI-610.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@BACSA_PESAJE","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bacsa.es\/fr\/producto\/indicateur-de-poids-bdi-610\/","url":"https:\/\/bacsa.es\/fr\/producto\/indicateur-de-poids-bdi-610\/","name":"Indicador de peso BDI-610","isPartOf":{"@id":"https:\/\/bacsa.es\/#website"},"datePublished":"2018-07-02T09:50:31+00:00","dateModified":"2020-04-29T19:16:46+00:00","breadcrumb":{"@id":"https:\/\/bacsa.es\/fr\/producto\/indicateur-de-poids-bdi-610\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bacsa.es\/fr\/producto\/indicateur-de-poids-bdi-610\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bacsa.es\/fr\/producto\/indicateur-de-poids-bdi-610\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/bacsa.es\/fr\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/bacsa.es\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"Indicateur de Poids BDI-610"}]},{"@type":"WebSite","@id":"https:\/\/bacsa.es\/#website","url":"https:\/\/bacsa.es\/","name":"Bacsa","description":"Calidad de Peso","publisher":{"@id":"https:\/\/bacsa.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bacsa.es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/bacsa.es\/#organization","name":"BACSA","url":"https:\/\/bacsa.es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/bacsa.es\/#\/schema\/logo\/image\/","url":"https:\/\/bacsa.es\/wp-content\/uploads\/2019\/01\/LOGO.png","contentUrl":"https:\/\/bacsa.es\/wp-content\/uploads\/2019\/01\/LOGO.png","width":1000,"height":215,"caption":"BACSA"},"image":{"@id":"https:\/\/bacsa.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Bacsa-142507322476303\/","https:\/\/twitter.com\/BACSA_PESAJE","https:\/\/www.linkedin.com\/company\/bacsa\/","https:\/\/www.youtube.com\/channel\/UCGm8hAnr6kEP21vdpU3jG9g"]}]}},"_links":{"self":[{"href":"https:\/\/bacsa.es\/fr\/wp-json\/wp\/v2\/product\/24775"}],"collection":[{"href":"https:\/\/bacsa.es\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bacsa.es\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/bacsa.es\/fr\/wp-json\/wp\/v2\/comments?post=24775"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bacsa.es\/fr\/wp-json\/wp\/v2\/media\/9155"}],"wp:attachment":[{"href":"https:\/\/bacsa.es\/fr\/wp-json\/wp\/v2\/media?parent=24775"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bacsa.es\/fr\/wp-json\/wp\/v2\/product_cat?post=24775"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bacsa.es\/fr\/wp-json\/wp\/v2\/product_tag?post=24775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}