{"id":10149,"date":"2017-05-27T09:33:53","date_gmt":"2017-05-27T08:33:53","guid":{"rendered":"https:\/\/bacsa.es\/servicios\/"},"modified":"2018-05-03T14:45:45","modified_gmt":"2018-05-03T13:45:45","slug":"services","status":"publish","type":"page","link":"https:\/\/bacsa.es\/fr\/services\/","title":{"rendered":"Services"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css=&#8221;.vc_custom_1509028396247{margin-top: 40px !important;}&#8221;][vc_column][vc_column_text]<\/p>\n<h2><strong>Service Technique<\/strong><\/h2>\n<h4>BACSA dispose de son propre Service Technique pour l&#8217;ensemble de ses produits avec des D\u00e9l\u00e9gations \u00e0 Barcelone, L\u00e9ride, Valence, S\u00e9ville, Grenade, Bourgos et Madrid, et \u00e0 travers de ses Agents Distributeurs pour le march\u00e9 international. Nous assistons \u00e0 nos Clients d&#8217;une mani\u00e8re imm\u00e9diate \u00e0 toutes les questions techniques.<\/h4>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_gmaps link=&#8221;#E-8_JTNDaWZyYW1lJTIwc3JjJTNEJTIyaHR0cHMlM0ElMkYlMkZ3d3cuZ29vZ2xlLmNvbSUyRm1hcHMlMkZlbWJlZCUzRnBiJTNEJTIxMW0xNCUyMTFtOCUyMTFtMyUyMTFkMTE5NDcuNTQyNDk4MTk2MDg4JTIxMmQyLjE1MjQ5NzklMjEzZDQxLjUyODQxODElMjEzbTIlMjExaTEwMjQlMjEyaTc2OCUyMTRmMTMuMSUyMTNtMyUyMTFtMiUyMTFzMHgwJTI1M0EweGFhODc2Yzk3MTIyZTZmN2YlMjEyc0JBQ1NBJTIxNWUwJTIxM20yJTIxMXNjYSUyMTJzZXMlMjE0djE1MDkwMjcyMTk2NDglMjIlMjB3aWR0aCUzRCUyMjYwMCUyMiUyMGhlaWdodCUzRCUyMjQ1MCUyMiUyMGZyYW1lYm9yZGVyJTNEJTIyMCUyMiUyMHN0eWxlJTNEJTIyYm9yZGVyJTNBMCUyMiUyMGFsbG93ZnVsbHNjcmVlbiUzRSUzQyUyRmlmcmFtZSUzRQ==&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<ul>\n<li>Le Service Technique, hautement qualifi\u00e9 <strong>avec plus de 35 ann\u00e9es d&#8217;exp\u00e9rience dans le secteur<\/strong>, nous permet d&#8217;aborder tout type de r\u00e9paration en instruments de pesage m\u00e9caniques et \u00e9lectroniques.<\/li>\n<li>Nous disposons aussi d&#8217;un service de <strong>d\u00e9montage et de montage de bascules qui requi\u00e8rent d\u00e9placer son emplacement<\/strong>, en aportant tous les moyens m\u00e9caniques, techniques et humains n\u00e9cessaires.<\/li>\n<li>Aussi nous offrons la<strong> transformation de bascules m\u00e9caniques en bascules \u00e9lectroniques<\/strong> en substituant les leviers par un ou plusieurs senseurs \u00e9lectroniques (capteurs de poids), et en ajoutant l&#8217;indicateur de poids correspondant.<\/li>\n<li>En conformit\u00e9 avec l&#8217;article 12.4 de la loi 32\/2014 de M\u00e9trologie,<strong>\u00a0BACSA est en condition de r\u00e9parer ses propres \u00e9quipes de pesage et les remettre en service sans la n\u00e9cessit\u00e9 d&#8217;une v\u00e9rification apr\u00e9s une r\u00e9paration de la part d&#8217;une Entit\u00e9 de V\u00e9rification<\/strong>. Cela suppose un grand b\u00e9n\u00e9fice pour notre Client: gain de temps et d&#8217;argent.<\/li>\n<li><strong>T\u00e9l\u00e9 maintenance<\/strong>, avec une attention t\u00e9l\u00e9phonique personnalis\u00e9e pour r\u00e9soudre les difficult\u00e9s de forme imm\u00e9diate.<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_cta h2=&#8221;Calibration et pesage d&#8217;instruments&#8221; txt_align=&#8221;center&#8221;]<a href=\"https:\/\/bacsa.es\/wp-content\/uploads\/2018\/01\/Calibracion-300x200.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-8975 aligncenter\" src=\"https:\/\/bacsa.es\/wp-content\/uploads\/2018\/01\/Calibracion-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a>Aussi bien chez le Client comme dans nos ateliers le Service Technique de BACSA peut r\u00e9aliser des calibrations de tout type de bascules \u00e9lectroniques, m\u00e9caniques et hybrides. BACSA offre le service de tra\u00e7abilit\u00e9 aux mod\u00e8les nationaux et Certificats ISO 9000.[\/vc_cta][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_cta h2=&#8221;V\u00e9rification pour la mise en service&#8221; txt_align=&#8221;center&#8221;]<a href=\"https:\/\/bacsa.es\/wp-content\/uploads\/2018\/01\/Verificacion-300x200.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-8978 aligncenter\" src=\"https:\/\/bacsa.es\/wp-content\/uploads\/2018\/01\/Verificacion-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a>BACSA dispose d&#8217;un service de qualit\u00e9 certifi\u00e9 en accord avec l&#8217;Annexe II.2 de la Directive 2014\/31\/UE, ce qui permet la mise en service des instruments de pesage sans besoin d&#8217;intervention d&#8217;autres agents. Cette mise en service est factible chez nous ou chez le Client.[\/vc_cta][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_cta h2=&#8221;Coordination de v\u00e9rifications p\u00e9riodiques&#8221; txt_align=&#8221;center&#8221;]<a href=\"https:\/\/bacsa.es\/wp-content\/uploads\/2018\/01\/Periodicas-300x225.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-8977 aligncenter\" src=\"https:\/\/bacsa.es\/wp-content\/uploads\/2018\/01\/Periodicas-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/><\/a>Nous offrons un service int\u00e9gral de coordinaci\u00f3n pour la v\u00e9rification p\u00e9riodique r\u00e9glementaire d&#8217;instruments de pesage. Nos Clients nous confient sur ce service o\u00f9 nous nous en chargeons de contracter, pr\u00eater service et coordonner toutes les activit\u00e9s et services n\u00e9cessaires pour la r\u00e9alisation de la v\u00e9rification avec assurance de bon r\u00e9sultat.[\/vc_cta][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_cta h2=&#8221;Actualization et formation permanente&#8221; txt_align=&#8221;center&#8221;]<a href=\"https:\/\/bacsa.es\/wp-content\/uploads\/2018\/01\/Formacion-300x225.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-8976 aligncenter\" src=\"https:\/\/bacsa.es\/wp-content\/uploads\/2018\/01\/Formacion-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/><\/a>Dans un monde en constante \u00e9volution technologique, la formation des utilisateurs devient essentielle pour un usage efficace et effectif de nos ressources humaines. Pour cela, nous disposons d&#8217;un service de formation adapt\u00e9 aux besoins de chaque parteneaire. Notre \u00e9quipe technique, par sa large trajectoire dans le monde du pesage, dispose de connaissances maximales et d&#8217;outils perfectionn\u00e9s pour une mise \u00e0 niveau renouvel\u00e9e.<\/p>\n<p>.[\/vc_cta][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1509028396247{margin-top: 40px !important;}&#8221;][vc_column][vc_column_text] Service Technique BACSA dispose de son propre Service Technique pour l&#8217;ensemble de ses produits avec des D\u00e9l\u00e9gations \u00e0 Barcelone, L\u00e9ride, Valence, S\u00e9ville, Grenade, Bourgos et Madrid, et \u00e0 travers de ses Agents Distributeurs pour le march\u00e9 international. Nous assistons \u00e0 nos Clients d&#8217;une mani\u00e8re imm\u00e9diate \u00e0 toutes les questions techniques. [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column [&hellip;]<\/p>\n","protected":false},"author":44,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bacsa: Soporte al cliente, servicio t\u00e9cnico y calibraciones.<\/title>\n<meta name=\"description\" content=\"El soporte y el servicio t\u00e9cnico son un tema clave en la gesti\u00f3n de las relaciones con los clientes de B\u00e1sculas y Arcas de Catalunya S.A.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bacsa.es\/fr\/services\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bacsa: Soporte al cliente, servicio t\u00e9cnico y calibraciones.\" \/>\n<meta property=\"og:description\" content=\"El soporte y el servicio t\u00e9cnico son un tema clave en la gesti\u00f3n de las relaciones con los clientes de B\u00e1sculas y Arcas de Catalunya S.A.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bacsa.es\/fr\/services\/\" \/>\n<meta property=\"og:site_name\" content=\"Bacsa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Bacsa-142507322476303\/\" \/>\n<meta property=\"article:modified_time\" content=\"2018-05-03T13:45:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bacsa.es\/wp-content\/uploads\/2018\/01\/Calibracion-300x200.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@BACSA_PESAJE\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bacsa.es\/fr\/services\/\",\"url\":\"https:\/\/bacsa.es\/fr\/services\/\",\"name\":\"Bacsa: Soporte al cliente, servicio t\u00e9cnico y calibraciones.\",\"isPartOf\":{\"@id\":\"https:\/\/bacsa.es\/#website\"},\"datePublished\":\"2017-05-27T08:33:53+00:00\",\"dateModified\":\"2018-05-03T13:45:45+00:00\",\"description\":\"El soporte y el servicio t\u00e9cnico son un tema clave en la gesti\u00f3n de las relaciones con los clientes de B\u00e1sculas y Arcas de Catalunya S.A.\",\"breadcrumb\":{\"@id\":\"https:\/\/bacsa.es\/fr\/services\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bacsa.es\/fr\/services\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bacsa.es\/fr\/services\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/bacsa.es\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Services\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bacsa.es\/#website\",\"url\":\"https:\/\/bacsa.es\/\",\"name\":\"Bacsa\",\"description\":\"Calidad de Peso\",\"publisher\":{\"@id\":\"https:\/\/bacsa.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bacsa.es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/bacsa.es\/#organization\",\"name\":\"BACSA\",\"url\":\"https:\/\/bacsa.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/bacsa.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/bacsa.es\/wp-content\/uploads\/2019\/01\/LOGO.png\",\"contentUrl\":\"https:\/\/bacsa.es\/wp-content\/uploads\/2019\/01\/LOGO.png\",\"width\":1000,\"height\":215,\"caption\":\"BACSA\"},\"image\":{\"@id\":\"https:\/\/bacsa.es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Bacsa-142507322476303\/\",\"https:\/\/twitter.com\/BACSA_PESAJE\",\"https:\/\/www.linkedin.com\/company\/bacsa\/\",\"https:\/\/www.youtube.com\/channel\/UCGm8hAnr6kEP21vdpU3jG9g\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bacsa: Soporte al cliente, servicio t\u00e9cnico y calibraciones.","description":"El soporte y el servicio t\u00e9cnico son un tema clave en la gesti\u00f3n de las relaciones con los clientes de B\u00e1sculas y Arcas de Catalunya S.A.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bacsa.es\/fr\/services\/","og_locale":"fr_FR","og_type":"article","og_title":"Bacsa: Soporte al cliente, servicio t\u00e9cnico y calibraciones.","og_description":"El soporte y el servicio t\u00e9cnico son un tema clave en la gesti\u00f3n de las relaciones con los clientes de B\u00e1sculas y Arcas de Catalunya S.A.","og_url":"https:\/\/bacsa.es\/fr\/services\/","og_site_name":"Bacsa","article_publisher":"https:\/\/www.facebook.com\/Bacsa-142507322476303\/","article_modified_time":"2018-05-03T13:45:45+00:00","og_image":[{"url":"https:\/\/bacsa.es\/wp-content\/uploads\/2018\/01\/Calibracion-300x200.jpg"}],"twitter_card":"summary_large_image","twitter_site":"@BACSA_PESAJE","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bacsa.es\/fr\/services\/","url":"https:\/\/bacsa.es\/fr\/services\/","name":"Bacsa: Soporte al cliente, servicio t\u00e9cnico y calibraciones.","isPartOf":{"@id":"https:\/\/bacsa.es\/#website"},"datePublished":"2017-05-27T08:33:53+00:00","dateModified":"2018-05-03T13:45:45+00:00","description":"El soporte y el servicio t\u00e9cnico son un tema clave en la gesti\u00f3n de las relaciones con los clientes de B\u00e1sculas y Arcas de Catalunya S.A.","breadcrumb":{"@id":"https:\/\/bacsa.es\/fr\/services\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bacsa.es\/fr\/services\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bacsa.es\/fr\/services\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/bacsa.es\/fr\/"},{"@type":"ListItem","position":2,"name":"Services"}]},{"@type":"WebSite","@id":"https:\/\/bacsa.es\/#website","url":"https:\/\/bacsa.es\/","name":"Bacsa","description":"Calidad de Peso","publisher":{"@id":"https:\/\/bacsa.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bacsa.es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/bacsa.es\/#organization","name":"BACSA","url":"https:\/\/bacsa.es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/bacsa.es\/#\/schema\/logo\/image\/","url":"https:\/\/bacsa.es\/wp-content\/uploads\/2019\/01\/LOGO.png","contentUrl":"https:\/\/bacsa.es\/wp-content\/uploads\/2019\/01\/LOGO.png","width":1000,"height":215,"caption":"BACSA"},"image":{"@id":"https:\/\/bacsa.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Bacsa-142507322476303\/","https:\/\/twitter.com\/BACSA_PESAJE","https:\/\/www.linkedin.com\/company\/bacsa\/","https:\/\/www.youtube.com\/channel\/UCGm8hAnr6kEP21vdpU3jG9g"]}]}},"_links":{"self":[{"href":"https:\/\/bacsa.es\/fr\/wp-json\/wp\/v2\/pages\/10149"}],"collection":[{"href":"https:\/\/bacsa.es\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bacsa.es\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bacsa.es\/fr\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/bacsa.es\/fr\/wp-json\/wp\/v2\/comments?post=10149"}],"version-history":[{"count":0,"href":"https:\/\/bacsa.es\/fr\/wp-json\/wp\/v2\/pages\/10149\/revisions"}],"wp:attachment":[{"href":"https:\/\/bacsa.es\/fr\/wp-json\/wp\/v2\/media?parent=10149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}